<p>Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema &#8222;Gesund durch den Herbst&#8220;.<br />
Viele von Ihnen beschäftigen sich bereits mit ätherischen Ölen, und gerade jetzt, in dieser Übergangszeit zwischen dem Sommer und der kalten Jahreszeit sind sie uns wichtige Helferlein.</p>
<p>Abgesehen vom <a href="https://aromaexperten.at/der-thymian-und-seine-chemotypen/">Thymian</a>, der im heurigen Jahr ja ziemlich &#8222;strapaziert&#8220; wurde, indem er zur Aromapflanze des Jahres gekürt wurde, gibt es noch eine Reihe anderer erkältungstauglicher ätherischer Öle, die in der Herbstzeit Eingang in unsere Überlegungen finden sollten.</p>
<p>Ein für mich typischer Herbstduft und besonders in der Übergangszeit wichtiges ätherisches Öl ist jedenfalls jenes der <strong><span style="color: #800080;">Myrte (<em>Myrtus communis</em>)</span></strong>. In der griechischen Sagenwelt ist die Myrte der Aphrodite geweiht, der Göttin der Schönheit und Liebe. Die Myrte steht &#8211; ebenso wie Aphrodite &#8211; für Jugend, Schönheit, Reinheit und Jungfräulichkeit.<br />
In den alpinen Regionen Österreichs (z.B. im steirischen Ennstal) wird bei der Geburt eines Mädchens ein Myrtenstock (als Zimmerpflanze) geschenkt. Diese Myrte wird gehegt und gepflegt und ein Zweiglein davon wird bei der Erstkommunion ans Kleidchen gesteckt, später dann eins bei der Firmung, und schlussendlich sollte das Pflänzchen so gut gedeihen, dass man daraus auch einen Brautkranz winden kann&#8230;</p>
<p>Botanisch gesehen handelt es sich bei der Myrte um einen immergrünen Strauch, der bis zu 5 m hoch werden kann. Die Blätter sind lanzettenförmig (allerdings nicht sehr groß), ledrig und glänzend. Und die Blüten sind weiß und duften sehr stark. Myrten wachsen natürlich im gesamten Mittelmeerraum, aber interessanterweise auch im Andengebiet (Südamerika). Blütezeit ist Mai bis Juli, dann bilden sich aus den Blüten die blau-schwarzen Beeren.</p>
<p>Die Myrte steht als Namenspatronin für die ganze Pflanzenfamilie der <span style="color: #800080;">Myrtengewächse</span> (<em>Myrtaceae</em>) und sie selbst ist wohl die einzige im Mittelmeerraum heimische Art dieser Pflanzenfamilie. Ihr frischer und etwas krautiger Duft wird &#8211; wenn die Sonne besonders warm vom Himmel strahlt &#8211; zum duftenden Begleiter beim Wandern in Korsika. Dieser Duft befreit vor allem die Atemwege, er gilt aber auch allgemein als immunstärkend.</p>
<p><a href="https://aromaexperten.at/files/2013/09/Myrtenblüte.jpg"><img loading="lazy" class="aligncenter size-full wp-image-1212" title="Myrtenblüte" src="https://aromaexperten.at/files/2013/09/Myrtenblüte.jpg" alt="Myrtenblüte" width="300" height="218" /></a></p>
<p>Das ätherische Öl wird aus den frischen Blättern und den Zweigspitzen hergestellt. Je nachdem, woher wir das ätherische Öl bekommen, kann es sich auch farblich unterscheiden. Und: auch beim Myrtenöl gibt es verschiedene Chemotypen, die ich Ihnen hier in Kurzform beschreiben möchte:</p>
<p><span style="color: #800080;"><strong>Myrte Anden</strong></span> stammt vorzugsweise aus Peru. Dieses ätherische Öl enthält keine Ester dafür aber ca. 75% Monoterpene (vor allem α-Pinen), ca. 10% Oxide (1,8-Cineol), bis zu 10% Monoterpenole (v.a. Linalool) und Sesquiterpene.</p>
<p><span style="color: #800080;"><strong>Myrte Türkisch</strong></span> oder Myrte ct. Cineol, auch Myrte grün enthält vor allem ca. 50% Oxide (1,8-Cineol), ca. 27% Monoterpene (α-Pinen), bis zu 10% Ester (Myrtenylacetat), ca. 10% Monoterpenole (Linalool) und Sesquiterpene. Diese Myrtenart ist nicht empfehlenswert für Kinder unter sechs Jahren, aber auch nicht für Kinder mit spastischen Atemwegserkrankungen, Asthmatiker, und bei körperlicher Anwendung nicht für empfindliche Haut.</p>
<p><span style="color: #800080;"><strong>Myrte Marokkanisch</strong></span> oder Myrte ct. myrtenylacetat oder auch Nordafrikanische Myrte besitzt vor allem ca. 45 &#8211; 50% Monoterpene (Limonen, α-Pinen, etc.), ca. 22-25% Ester (Myrtenylacetat), ca. 17 &#8211; 45% Oxide (1,8-Cineol) und bis zu 10% Monoterpenole (Linalool). Dieses ätherische Öl können Sie auch für kleinere Kinder verwenden (natürlich in der entsprechenden Verdünnung).</p>
<p>Ein relativ großes Anbaugebiet für Myrte finden wir auf der Insel Korsika. Dieses Öl zeichnet sich durch eine brilliant grüne Farbe und einen hohen Gehalt an 1,8-Cineol aus. Es wird nur für die Aromatherapie angebaut und hat einen erstaunlich entspannenden Effekt, wenn man den Duft direkt einatmet.</p>
<p>Für mich ist es eine wunderbare Möglichkeit, bei Grippe, Husten, Heiserkeit, Bronchitis, Nebenhöhlenproblemen und zur Immunstärkung duftende Pflege einzusetzen. Myrte &#8211; welche auch immer Ihr Favorit wird &#8211; hat eine sehr starke antiseptische Wirkung und eignet sich gut zur Erfrischung der Raumluft.<br />
Myrtenöl kann auch als sanfte Komponente in naturkosmetischen Produkten eingesetzt werden: hier kann es seine regenerierende, straffende und antiallergische Wirkung am besten entfalten.</p>
<p><span style="color: #800080;"><strong>Deospray mit Myrtenhydrolat:</strong></span><br />
100 ml Myrtenhydrolat<br />
9 Tropfen Myrte<br />
3 Tropfen Lavendelsalbei<br />
3 Tropfen Lavandin super<br />
4 Tropfen Atlaszeder</p>
<p>&nbsp;</p>
<p>&nbsp;</p>
<p>&nbsp;</p>
<div class="shariff shariff-align-center shariff-widget-align-left shariff-buttonstretch"><ul class="shariff-buttons theme-white orientation-horizontal buttonsize-small"><li class="shariff-button facebook shariff-nocustomcolor" style="background-color:#4273c8"><a href="https://www.facebook.com/sharer/sharer.php?u=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F" title="Bei Facebook teilen" aria-label="Bei Facebook teilen" role="button" rel="nofollow" class="shariff-link" style="; background-color:#3b5998; color:#3b5998" target="_blank"><span class="shariff-icon" style="fill:#3b5998"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 18 32"><path fill="#3b5998" d="M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z"/></svg></span><span class="shariff-text" style="color:#3b5998">teilen</span>&nbsp;</a></li><li class="shariff-button twitter shariff-nocustomcolor" style="background-color:#595959"><a href="https://twitter.com/share?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F&text=Gesund%20durch%20den%20Herbst" title="Bei X teilen" aria-label="Bei X teilen" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#000; color:#000" target="_blank"><span class="shariff-icon" style="fill:#000"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 24 24"><path fill="#000" d="M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0"/></svg></span><span class="shariff-text" style="color:#000">teilen</span>&nbsp;</a></li><li class="shariff-button pinterest shariff-nocustomcolor" style="background-color:#e70f18"><a href="https://www.pinterest.com/pin/create/link/?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F&media=https%3A%2F%2Faromaexperten.at%2Ffiles%2F2013%2F09%2FMyrtenbl%C3%BCte.jpg&description=Gesund%20durch%20den%20Herbst" title="Bei Pinterest pinnen" aria-label="Bei Pinterest pinnen" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#cb2027; color:#cb2027" target="_blank"><span class="shariff-icon" style="fill:#cb2027"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 27 32"><path fill="#cb2027" d="M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z"/></svg></span><span class="shariff-text" style="color:#cb2027">merken</span>&nbsp;</a></li><li class="shariff-button xing shariff-nocustomcolor" style="background-color:#29888a"><a href="https://www.xing.com/spi/shares/new?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F" title="Bei XING teilen" aria-label="Bei XING teilen" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#126567; color:#126567" target="_blank"><span class="shariff-icon" style="fill:#126567"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 25 32"><path fill="#126567" d="M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z"/></svg></span><span class="shariff-text" style="color:#126567">teilen</span>&nbsp;</a></li><li class="shariff-button linkedin shariff-nocustomcolor" style="background-color:#1488bf"><a href="https://www.linkedin.com/sharing/share-offsite/?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F" title="Bei LinkedIn teilen" aria-label="Bei LinkedIn teilen" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#0077b5; color:#0077b5" target="_blank"><span class="shariff-icon" style="fill:#0077b5"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 27 32"><path fill="#0077b5" d="M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z"/></svg></span><span class="shariff-text" style="color:#0077b5">teilen</span>&nbsp;</a></li><li class="shariff-button rss shariff-nocustomcolor" style="background-color:#ff8c00"><a href="https://fengshui-austria.com/aromaexpertenalt/feed/rss/" title="RSS-feed" aria-label="RSS-feed" role="button" class="shariff-link" style="; background-color:#fe9312; color:#fe9312" target="_blank"><span class="shariff-icon" style="fill:#fe9312"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 32 32"><path fill="#fe9312" d="M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z"/></svg></span><span class="shariff-text" style="color:#fe9312">RSS-feed</span>&nbsp;</a></li><li class="shariff-button sms shariff-nocustomcolor shariff-mobile" style="background-color:#d7d9d8"><a href="sms:?&body=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F" title="Per SMS teilen" aria-label="Per SMS teilen" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#a1e877; color:#a1e877" target="_blank"><span class="shariff-icon" style="fill:#a1e877"><svg xmlns="http://www.w3.org/2000/svg" width="510" height="510" viewBox="0 0 510 510"><path fill="#a1e877" d="M459 0H51C23 0 0 23 0 51v459l102-102h357c28.1 0 51-22.9 51-51V51C510 23 487.1 0 459 0zM178.5 229.5h-51v-51h51V229.5zM280.5 229.5h-51v-51h51V229.5zM382.5 229.5h-51v-51h51V229.5z"/></svg></span><span class="shariff-text" style="color:#a1e877">teilen</span>&nbsp;</a></li><li class="shariff-button whatsapp shariff-nocustomcolor" style="background-color:#5cbe4a"><a href="https://api.whatsapp.com/send?text=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F%20Gesund%20durch%20den%20Herbst" title="Bei Whatsapp teilen" aria-label="Bei Whatsapp teilen" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#34af23; color:#34af23" target="_blank"><span class="shariff-icon" style="fill:#34af23"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 32 32"><path fill="#34af23" d="M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z"/></svg></span><span class="shariff-text" style="color:#34af23">teilen</span>&nbsp;</a></li><li class="shariff-button mailto shariff-nocustomcolor" style="background-color:#a8a8a8"><a href="mailto:?body=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F&subject=Gesund%20durch%20den%20Herbst" title="Per E-Mail versenden" aria-label="Per E-Mail versenden" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#999; color:#999"><span class="shariff-icon" style="fill:#999"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 32 32"><path fill="#999" d="M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z"/></svg></span><span class="shariff-text" style="color:#999">E-Mail</span>&nbsp;</a></li><li class="shariff-button printer shariff-nocustomcolor" style="background-color:#a8a8a8"><a href="javascript:window.print()" title="drucken" aria-label="drucken" role="button" rel="noopener nofollow" class="shariff-link" style="; background-color:#999; color:#999"><span class="shariff-icon" style="fill:#999"><svg width="32px" height="20px" xmlns="http://www.w3.org/2000/svg" viewBox="0 0 30 32"><path fill="#999" d="M6.8 27.4h16v-4.6h-16v4.6zM6.8 16h16v-6.8h-2.8q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-11.4v11.4zM27.4 17.2q0-0.5-0.3-0.8t-0.8-0.4-0.8 0.4-0.3 0.8 0.3 0.8 0.8 0.3 0.8-0.3 0.3-0.8zM29.7 17.2v7.4q0 0.2-0.2 0.4t-0.4 0.2h-4v2.8q0 0.7-0.5 1.2t-1.2 0.5h-17.2q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-4q-0.2 0-0.4-0.2t-0.2-0.4v-7.4q0-1.4 1-2.4t2.4-1h1.2v-9.7q0-0.7 0.5-1.2t1.2-0.5h12q0.7 0 1.6 0.4t1.3 0.8l2.7 2.7q0.5 0.5 0.9 1.4t0.4 1.6v4.6h1.1q1.4 0 2.4 1t1 2.4z"/></svg></span><span class="shariff-text" style="color:#999">drucken</span>&nbsp;</a></li></ul></div>{"id":1211,"date":"2013-09-13T14:35:30","date_gmt":"2013-09-13T12:35:30","guid":{"rendered":"https:\/\/aromaexperten.at\/?p=1211"},"modified":"2018-05-30T12:19:13","modified_gmt":"2018-05-30T10:19:13","slug":"gesund-durch-den-herbst","status":"publish","type":"post","link":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/","title":{"rendered":"Gesund durch den Herbst"},"content":{"rendered":"<p>Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema &#8222;Gesund durch den Herbst&#8220;.<br \/>\nViele von Ihnen besch\u00e4ftigen sich bereits mit \u00e4therischen \u00d6len, und gerade jetzt, in dieser \u00dcbergangszeit zwischen dem Sommer und der kalten Jahreszeit sind sie uns wichtige Helferlein.<\/p>\n<p>Abgesehen vom <a href=\"https:\/\/aromaexperten.at\/der-thymian-und-seine-chemotypen\/\">Thymian<\/a>, der im heurigen Jahr ja ziemlich &#8222;strapaziert&#8220; wurde, indem er zur Aromapflanze des Jahres gek\u00fcrt wurde, gibt es noch eine Reihe anderer erk\u00e4ltungstauglicher \u00e4therischer \u00d6le, die in der Herbstzeit Eingang in unsere \u00dcberlegungen finden sollten.<\/p>\n<p>Ein f\u00fcr mich typischer Herbstduft und besonders in der \u00dcbergangszeit wichtiges \u00e4therisches \u00d6l ist jedenfalls jenes der <strong><span style=\"color: #800080;\">Myrte (<em>Myrtus communis<\/em>)<\/span><\/strong>. In der griechischen Sagenwelt ist die Myrte der Aphrodite geweiht, der G\u00f6ttin der Sch\u00f6nheit und Liebe. Die Myrte steht &#8211; ebenso wie Aphrodite &#8211; f\u00fcr Jugend, Sch\u00f6nheit, Reinheit und Jungfr\u00e4ulichkeit.<br \/>\nIn den alpinen Regionen \u00d6sterreichs (z.B. im steirischen Ennstal) wird bei der Geburt eines M\u00e4dchens ein Myrtenstock (als Zimmerpflanze) geschenkt. Diese Myrte wird gehegt und gepflegt und ein Zweiglein davon wird bei der Erstkommunion ans Kleidchen gesteckt, sp\u00e4ter dann eins bei der Firmung, und schlussendlich sollte das Pfl\u00e4nzchen so gut gedeihen, dass man daraus auch einen Brautkranz winden kann&#8230;<\/p>\n<p>Botanisch gesehen handelt es sich bei der Myrte um einen immergr\u00fcnen Strauch, der bis zu 5 m hoch werden kann. Die Bl\u00e4tter sind lanzettenf\u00f6rmig (allerdings nicht sehr gro\u00df), ledrig und gl\u00e4nzend. Und die Bl\u00fcten sind wei\u00df und duften sehr stark. Myrten wachsen nat\u00fcrlich im gesamten Mittelmeerraum, aber interessanterweise auch im Andengebiet (S\u00fcdamerika). Bl\u00fctezeit ist Mai bis Juli, dann bilden sich aus den Bl\u00fcten die blau-schwarzen Beeren.<\/p>\n<p>Die Myrte steht als Namenspatronin f\u00fcr die ganze Pflanzenfamilie der <span style=\"color: #800080;\">Myrtengew\u00e4chse<\/span> (<em>Myrtaceae<\/em>) und sie selbst ist wohl die einzige im Mittelmeerraum heimische Art dieser Pflanzenfamilie. Ihr frischer und etwas krautiger Duft wird &#8211; wenn die Sonne besonders warm vom Himmel strahlt &#8211; zum duftenden Begleiter beim Wandern in Korsika. Dieser Duft befreit vor allem die Atemwege, er gilt aber auch allgemein als immunst\u00e4rkend.<\/p>\n<p><a href=\"https:\/\/aromaexperten.at\/files\/2013\/09\/Myrtenbl\u00fcte.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1212\" title=\"Myrtenbl\u00fcte\" src=\"https:\/\/aromaexperten.at\/files\/2013\/09\/Myrtenbl\u00fcte.jpg\" alt=\"Myrtenbl\u00fcte\" width=\"300\" height=\"218\" \/><\/a><\/p>\n<p>Das \u00e4therische \u00d6l wird aus den frischen Bl\u00e4ttern und den Zweigspitzen hergestellt. Je nachdem, woher wir das \u00e4therische \u00d6l bekommen, kann es sich auch farblich unterscheiden. Und: auch beim Myrten\u00f6l gibt es verschiedene Chemotypen, die ich Ihnen hier in Kurzform beschreiben m\u00f6chte:<\/p>\n<p><span style=\"color: #800080;\"><strong>Myrte Anden<\/strong><\/span> stammt vorzugsweise aus Peru. Dieses \u00e4therische \u00d6l enth\u00e4lt keine Ester daf\u00fcr aber ca. 75% Monoterpene (vor allem \u03b1-Pinen), ca. 10% Oxide (1,8-Cineol), bis zu 10% Monoterpenole (v.a. Linalool) und Sesquiterpene.<\/p>\n<p><span style=\"color: #800080;\"><strong>Myrte T\u00fcrkisch<\/strong><\/span> oder Myrte ct. Cineol, auch Myrte gr\u00fcn enth\u00e4lt vor allem ca. 50% Oxide (1,8-Cineol), ca. 27% Monoterpene (\u03b1-Pinen), bis zu 10% Ester (Myrtenylacetat), ca. 10% Monoterpenole (Linalool) und Sesquiterpene. Diese Myrtenart ist nicht empfehlenswert f\u00fcr Kinder unter sechs Jahren, aber auch nicht f\u00fcr Kinder mit spastischen Atemwegserkrankungen, Asthmatiker, und bei k\u00f6rperlicher Anwendung nicht f\u00fcr empfindliche Haut.<\/p>\n<p><span style=\"color: #800080;\"><strong>Myrte Marokkanisch<\/strong><\/span> oder Myrte ct. myrtenylacetat oder auch Nordafrikanische Myrte besitzt vor allem ca. 45 &#8211; 50% Monoterpene (Limonen, \u03b1-Pinen, etc.), ca. 22-25% Ester (Myrtenylacetat), ca. 17 &#8211; 45% Oxide (1,8-Cineol) und bis zu 10% Monoterpenole (Linalool). Dieses \u00e4therische \u00d6l k\u00f6nnen Sie auch f\u00fcr kleinere Kinder verwenden (nat\u00fcrlich in der entsprechenden Verd\u00fcnnung).<\/p>\n<p>Ein relativ gro\u00dfes Anbaugebiet f\u00fcr Myrte finden wir auf der Insel Korsika. Dieses \u00d6l zeichnet sich durch eine brilliant gr\u00fcne Farbe und einen hohen Gehalt an 1,8-Cineol aus. Es wird nur f\u00fcr die Aromatherapie angebaut und hat einen erstaunlich entspannenden Effekt, wenn man den Duft direkt einatmet.<\/p>\n<p>F\u00fcr mich ist es eine wunderbare M\u00f6glichkeit, bei Grippe, Husten, Heiserkeit, Bronchitis, Nebenh\u00f6hlenproblemen und zur Immunst\u00e4rkung duftende Pflege einzusetzen. Myrte &#8211; welche auch immer Ihr Favorit wird &#8211; hat eine sehr starke antiseptische Wirkung und eignet sich gut zur Erfrischung der Raumluft.<br \/>\nMyrten\u00f6l kann auch als sanfte Komponente in naturkosmetischen Produkten eingesetzt werden: hier kann es seine regenerierende, straffende und antiallergische Wirkung am besten entfalten.<\/p>\n<p><span style=\"color: #800080;\"><strong>Deospray mit Myrtenhydrolat:<\/strong><\/span><br \/>\n100 ml Myrtenhydrolat<br \/>\n9 Tropfen Myrte<br \/>\n3 Tropfen Lavendelsalbei<br \/>\n3 Tropfen Lavandin super<br \/>\n4 Tropfen Atlaszeder<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"shariff shariff-align-center shariff-widget-align-left shariff-buttonstretch\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F&text=Gesund%20durch%20den%20Herbst\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F&media=https%3A%2F%2Faromaexperten.at%2Ffiles%2F2013%2F09%2FMyrtenbl%C3%BCte.jpg&description=Gesund%20durch%20den%20Herbst\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#cb2027\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#cb2027\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#cb2027\">merken<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#126567\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#126567\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#126567\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#0077b5\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0077b5\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0077b5\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button rss shariff-nocustomcolor\" style=\"background-color:#ff8c00\"><a href=\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/feed\/rss\/\" title=\"RSS-feed\" aria-label=\"RSS-feed\" role=\"button\" class=\"shariff-link\" style=\"; background-color:#fe9312; color:#fe9312\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#fe9312\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fe9312\" d=\"M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#fe9312\">RSS-feed<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button sms shariff-nocustomcolor shariff-mobile\" style=\"background-color:#d7d9d8\"><a href=\"sms:?&body=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F\" title=\"Per SMS teilen\" aria-label=\"Per SMS teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#a1e877; color:#a1e877\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#a1e877\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510\" height=\"510\" viewBox=\"0 0 510 510\"><path fill=\"#a1e877\" d=\"M459 0H51C23 0 0 23 0 51v459l102-102h357c28.1 0 51-22.9 51-51V51C510 23 487.1 0 459 0zM178.5 229.5h-51v-51h51V229.5zM280.5 229.5h-51v-51h51V229.5zM382.5 229.5h-51v-51h51V229.5z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#a1e877\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F%20Gesund%20durch%20den%20Herbst\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#34af23\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#34af23\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#34af23\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Ffengshui-austria.com%2Faromaexpertenalt%2Fgesund-durch-den-herbst%2F&subject=Gesund%20durch%20den%20Herbst\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#999\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#999\">E-Mail<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button printer shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"javascript:window.print()\" title=\"drucken\" aria-label=\"drucken\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#999\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 30 32\"><path fill=\"#999\" d=\"M6.8 27.4h16v-4.6h-16v4.6zM6.8 16h16v-6.8h-2.8q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-11.4v11.4zM27.4 17.2q0-0.5-0.3-0.8t-0.8-0.4-0.8 0.4-0.3 0.8 0.3 0.8 0.8 0.3 0.8-0.3 0.3-0.8zM29.7 17.2v7.4q0 0.2-0.2 0.4t-0.4 0.2h-4v2.8q0 0.7-0.5 1.2t-1.2 0.5h-17.2q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-4q-0.2 0-0.4-0.2t-0.2-0.4v-7.4q0-1.4 1-2.4t2.4-1h1.2v-9.7q0-0.7 0.5-1.2t1.2-0.5h12q0.7 0 1.6 0.4t1.3 0.8l2.7 2.7q0.5 0.5 0.9 1.4t0.4 1.6v4.6h1.1q1.4 0 2.4 1t1 2.4z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#999\">drucken<\/span>&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[455,17,452,26,45,46,43,100,104,106,167],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gesund durch den Herbst &bull;<\/title>\n<meta name=\"description\" content=\"Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema &quot;Gesund durch den Herbst&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesund durch den Herbst &bull;\" \/>\n<meta property=\"og:description\" content=\"Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema &quot;Gesund durch den Herbst&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/\" \/>\n<meta property=\"og:site_name\" content=\"Alte Aromaexperten.at\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aromaexperten\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/ingrid.kleindienst\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-13T12:35:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-30T10:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aromaexperten.at\/files\/2013\/09\/Myrtenbl\u00fcte.jpg\" \/>\n<meta name=\"author\" content=\"Ingrid\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@gucki849kurt\" \/>\n<meta name=\"twitter:site\" content=\"@gucki849kurt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ingrid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#website\",\"url\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/\",\"name\":\"Alte Aromaexperten.at\",\"description\":\"Ausbildungen mit Qualit\u00e4tsgarantie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/\",\"url\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/\",\"name\":\"Gesund durch den Herbst &bull;\",\"isPartOf\":{\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#website\"},\"datePublished\":\"2013-09-13T12:35:30+00:00\",\"dateModified\":\"2018-05-30T10:19:13+00:00\",\"author\":{\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#\/schema\/person\/9aa6639f1e3b5771b76b959d4cad6368\"},\"description\":\"Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema \\\"Gesund durch den Herbst\\\".\",\"breadcrumb\":{\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Gesund durch den Herbst\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#\/schema\/person\/9aa6639f1e3b5771b76b959d4cad6368\",\"name\":\"Ingrid\",\"sameAs\":[\"http:\/\/www.kleindienst-john.at\",\"https:\/\/facebook.com\/ingrid.kleindienst\",\"https:\/\/instagram.com\/kleindienstjohn\",\"https:\/\/linkedin.com\/ingrid.kleindienst\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesund durch den Herbst &bull;","description":"Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema \"Gesund durch den Herbst\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/","og_locale":"de_DE","og_type":"article","og_title":"Gesund durch den Herbst &bull;","og_description":"Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema \"Gesund durch den Herbst\".","og_url":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/","og_site_name":"Alte Aromaexperten.at","article_publisher":"https:\/\/www.facebook.com\/aromaexperten","article_author":"https:\/\/facebook.com\/ingrid.kleindienst","article_published_time":"2013-09-13T12:35:30+00:00","article_modified_time":"2018-05-30T10:19:13+00:00","og_image":[{"url":"https:\/\/aromaexperten.at\/files\/2013\/09\/Myrtenbl\u00fcte.jpg"}],"author":"Ingrid","twitter_card":"summary","twitter_creator":"@gucki849kurt","twitter_site":"@gucki849kurt","twitter_misc":{"Verfasst von":"Ingrid","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#website","url":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/","name":"Alte Aromaexperten.at","description":"Ausbildungen mit Qualit\u00e4tsgarantie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/","url":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/","name":"Gesund durch den Herbst &bull;","isPartOf":{"@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#website"},"datePublished":"2013-09-13T12:35:30+00:00","dateModified":"2018-05-30T10:19:13+00:00","author":{"@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#\/schema\/person\/9aa6639f1e3b5771b76b959d4cad6368"},"description":"Nach einer kleinen gesundheitsbedingten Auszeit melde ich mich heute wieder mal mit einem Beitrag, diesmal zum Thema \"Gesund durch den Herbst\".","breadcrumb":{"@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/gesund-durch-den-herbst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Gesund durch den Herbst"}]},{"@type":"Person","@id":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/#\/schema\/person\/9aa6639f1e3b5771b76b959d4cad6368","name":"Ingrid","sameAs":["http:\/\/www.kleindienst-john.at","https:\/\/facebook.com\/ingrid.kleindienst","https:\/\/instagram.com\/kleindienstjohn","https:\/\/linkedin.com\/ingrid.kleindienst"]}]}},"_links":{"self":[{"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/posts\/1211"}],"collection":[{"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/comments?post=1211"}],"version-history":[{"count":1,"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/posts\/1211\/revisions"}],"predecessor-version":[{"id":1213,"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/posts\/1211\/revisions\/1213"}],"wp:attachment":[{"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/media?parent=1211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/categories?post=1211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fengshui-austria.com\/aromaexpertenalt\/wp-json\/wp\/v2\/tags?post=1211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}